{"id":246,"date":"2024-02-22T14:36:36","date_gmt":"2024-02-22T14:36:36","guid":{"rendered":"https:\/\/www.livingpillow.com\/archives\/246"},"modified":"2024-02-22T14:36:36","modified_gmt":"2024-02-22T14:36:36","slug":"la-nostra-garanzia","status":"publish","type":"post","link":"https:\/\/www.livingpillow.com\/it\/help\/our-guarantee\/","title":{"rendered":"La nostra garanzia"},"content":{"rendered":"<p><strong><b>Attenzione professionale, cura professionale<\/b><\/strong><\/p>\n<p><strong><b>Cuscino vivente<\/b><\/strong><strong><b>\u00a0Controllo qualit\u00e0 dall'approvvigionamento alla consegna<\/b><\/strong><\/p>\n<p>Vi siete mai chiesti che cosa ha fatto il vostro articolo appena acquistato per arrivare sano e salvo alla vostra porta di casa? Su LivingPillow.com, ancor prima che l'ordine venga effettuato - sia che si tratti di un grossista, di un distributore o di qualcuno che sta semplicemente cercando di acquistare l'ultimo gadget - i nostri prodotti vengono inseriti in un sistema che controlla e ricontrolla la qualit\u00e0, dall'approvvigionamento alla consegna.<\/p>\n<p><strong><b>Approvvigionamento dei prodotti<\/b><\/strong><\/p>\n<p>Mentre voi siete seduti nel vostro comodo ufficio o a casa a curiosare nella vasta gamma di prodotti di LivingPillow, noi siamo gi\u00e0 impegnati a selezionare i migliori prodotti al miglior prezzo, pensando a voi, il cliente. LivingPillow seleziona per qualit\u00e0 dei prodotti, reputazione e affidabilit\u00e0. Dopo un rigoroso processo di ispezione e verifica dei prodotti che sappiamo interessare agli acquirenti, li rendiamo disponibili a prezzi imbattibili.<strong><b>\u00a0<\/b><\/strong><\/p>\n<p><strong><b>Elaborazione dell'ordine del prodotto<\/b><\/strong><\/p>\n<p>Quando l'ordine viene pagato correttamente, i nostri colleghi di LivingPillow entrano in azione e iniziano immediatamente a elaborare l'ordine. Una persona esamina i dettagli dell'ordine, controllando che non ci siano ritardi nell'elaborazione, mentre un'altra si occupa di prelevare l'inventario dai nostri scaffali. Nel frattempo, un'e-mail di conferma dell'ordine sar\u00e0 gi\u00e0 arrivata nella vostra e-mail registrata.<\/p>\n<p><strong><b>Testare i prodotti<\/b><\/strong><\/p>\n<p>Anche se i nostri articoli di qualit\u00e0 sono altamente affidabili, non corriamo alcun rischio con il vostro ordine specifico. Tutti i prodotti sono sottoposti a un'esauriente procedura di controllo qualit\u00e0: ogni prodotto viene inviato al nostro centro di distribuzione, dove un team di ispezione altamente qualificato valuta i vostri prodotti in base a protocolli e requisiti di ispezione rigorosi. Abbiamo eseguito bene il vostro ordine? Prima di iniziare l'imballaggio, effettuiamo un controllo approfondito per abbinare correttamente gli ordini.<\/p>\n<p>Il nostro team di controllo qualit\u00e0 sottopone il prodotto a un'ulteriore ispezione, interna ed esterna, seguendo protocolli e requisiti rigorosi.<\/p>\n<p>Se il prodotto soddisfa i nostri standard, sar\u00e0 pronto per essere spedito a voi!<\/p>\n<p><strong><b>Imballaggio dei prodotti<\/b><\/strong><\/p>\n<p>Il team di imballaggio e consegna di LivingPillow funziona come un orologio, anche se lo diciamo noi stessi. Prima di essere spediti, gli articoli vengono sempre accuratamente ispezionati per verificare la presenza di eventuali difetti di produzione e di design, per garantire che l'articolo di cui vi siete innamorati online sia quello che riceverete dal nostro corriere. I membri del nostro team controllano le ricevute d'ordine con la conferma d'acquisto originale online e poi esaminano il prodotto prelevato dallo scaffale per assicurarsi che corrisponda a quello elencato.<\/p>\n<p>Poi, e solo allora, il team passa all'imballaggio dell'ordine, raddoppiando (e spesso aumentando) il pluriball e il nastro adesivo. Quindi, l'ordine esce dalla porta in mani sicure con i nostri corrieri fidati e verificati.<\/p>\n<p><strong><b>Tracciamento dei prodotti<\/b><\/strong><\/p>\n<p>Una volta che il vostro prodotto ha lasciato le nostre porte, siamo ancora qui per aiutarvi. Il team del Servizio Clienti di LivingPillow \u00e8 sempre al lavoro dietro le quinte per rispondere a ogni vostra esigenza e richiesta. Seguiamo le vostre spedizioni e siamo a vostra disposizione per rispondere a qualsiasi domanda. Non importa quale sia il problema, siamo sempre qui per servirvi.<\/p>","protected":false},"excerpt":{"rendered":"<p>Professional Attention, Professional Care LivingPillow\u00a0Quality Control From Sourcing to Delivery Ever wonder what your newly-purchased item went through to arrive safely at your doorstep? At LivingPillow.com, even before your order is placed \u2013 whether as a wholesaler, distributor, or someone who\u2019s just looking to buy the latest gadget \u2013 our products are streamlined into a [&#8230;]\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-246","post","type-post","status-publish","format-standard","hentry","category-help"],"_links":{"self":[{"href":"https:\/\/www.livingpillow.com\/it\/wp-json\/wp\/v2\/posts\/246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livingpillow.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livingpillow.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livingpillow.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livingpillow.com\/it\/wp-json\/wp\/v2\/comments?post=246"}],"version-history":[{"count":0,"href":"https:\/\/www.livingpillow.com\/it\/wp-json\/wp\/v2\/posts\/246\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.livingpillow.com\/it\/wp-json\/wp\/v2\/media?parent=246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livingpillow.com\/it\/wp-json\/wp\/v2\/categories?post=246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livingpillow.com\/it\/wp-json\/wp\/v2\/tags?post=246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}